{"id":22,"count":34,"description":"Ejercicios de examen para M\u00e9todos Num\u00e9ricos","link":"https:\/\/blog.espol.edu.ec\/algoritmos101\/category\/mn-2eva30\/","name":"MN 2Eva 2021-2025","slug":"mn-2eva30","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/categories\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/posts?categories=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}