{"id":11227,"date":"2025-07-01T22:49:32","date_gmt":"2025-07-02T03:49:32","guid":{"rendered":"http:\/\/blog.espol.edu.ec\/analisisnumerico\/?p=11227"},"modified":"2026-08-09T17:05:47","modified_gmt":"2026-08-09T22:05:47","slug":"1eva2025paoi_t3-ruta-avistamiento-ballenas","status":"publish","type":"post","link":"https:\/\/blog.espol.edu.ec\/algoritmos101\/mn-1eva30\/1eva2025paoi_t3-ruta-avistamiento-ballenas\/","title":{"rendered":"1Eva2025PAOI_T3 Ruta de avistamiento ballenas"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">1ra Evaluaci\u00f3n 2025-2026 PAO I. 1\/Julio\/2025<\/h2>\n\n\n\n<p><strong>Tema 3<\/strong> (30 puntos) El avistamiento de ballenas es una actividad popular en Ecuador que atrae a miles de&nbsp;turistas cada a\u00f1o.<\/p>\n\n\n\n<figure class=\"wp-block-image alignright size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"425\" src=\"http:\/\/blog.espol.edu.ec\/algoritmos101\/files\/2025\/07\/avistamientoBallenasEcuador01.png\" alt=\"avistamiento Ballenas Ecuador\" class=\"wp-image-14292\" \/><\/figure>\n\n\n\n<p>Puerto L\u00f3pez, en la provincia de Manab\u00ed, a 219 kil\u00f3metros de Guayaquil, es uno de los epicentros de esta actividad.<br>Esta peque\u00f1a localidad costera celebra anualmente el Festival de Observaci\u00f3n de Ballenas Jorobadas.<\/p>\n\n\n\n<p>El evento busca promover el turismo y la importancia de la conservaci\u00f3n marina.<\/p>\n\n\n\n<p>Usando los registros de coordenadas (<em>relativas x,y<\/em>) donde se han observado las ballenas, realice el trazado de una ruta de avistamiento tur\u00edstico siguiendo el viaje de las ballenas.<\/p>\n\n\n\n<p>Los puntos registrados son:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>x<\/td><td>1.03<\/td><td>2.2<\/td><td>3.6<\/td><td>4.24<\/td><td>5.3<\/td><\/tr><tr><td>y<\/td><td>-0.5<\/td><td>0.7<\/td><td>4.1<\/td><td>2.3<\/td><td>0.1<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>a. Describa el planteamiento del ejercicio, justificando el grado del polinomio seleccionado.<\/p>\n\n\n\n<p>b. Realice el desarrollo anal\u00edtico para la ruta de avistamiento, usando interpolaci\u00f3n de Lagrange<\/p>\n\n\n\n<p>c. Presente el polinomio simplificado usando el algoritmo.<\/p>\n\n\n\n<p>d. Verifique que el polinomio pasa por los puntos usados para el planteamiento usando una gr\u00e1fica. Observe y comente sus resultados<\/p>\n\n\n\n<p>e. Adjunte algoritmo.py, resultados.txt y gr\u00e1fica.png en \u201caulavirtual\u201d.<\/p>\n\n\n\n<p><strong>R\u00fabrica<\/strong>: literal a (5 puntos), literal b (10 puntos), literal c (5 puntos), literal d (5 puntos), literal e (5 puntos)<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>xi = &#091; 1.03, 2.2, 3.6, 4.24, 5.3]\nyi = &#091;-0.5 , 0.7, 4.1, 2.3,  0.1]<\/code><\/pre>\n\n\n\n<p><strong>Referencia<\/strong>: [1] Turistas asombrados por avistamiento de ballena blanca en la costa de Ecuador. Teleamazonas.com. 24-junio-2025 https:\/\/www.teleamazonas.com\/tendencias\/turistas-asombrados-avistamiento-ballena-blanca-costa-ecuador-97688\/<\/p>\n\n\n\n<p>[2] El impresionante viaje de las ballenas jorobadas a Ecuador. Yalil\u00e9 Loaiza, Infobae. 30 junio 2024. https:\/\/www.infobae.com\/america\/america-latina\/2024\/06\/30\/el-impresionante-viaje-de-las-ballenas-jorobadas-a-ecuador\/<\/p>\n\n\n\n<p>[3] Primer avistamiento de una ballena blanca en Ecuador. Televistazo-Ecuavisa. 24-Junio-2025.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Primer avistamiento de una ballena blanca en Ecuador | Televistazo | Ecuavisa\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/tpA0qy1wa0M?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>[4] Inicia temporada de avistamiento de ballenas en la costa. Televistazo-Ecuavisa.18-junio-2024.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Inicia temporada de avistamiento de ballenas en la costa | Televistazo | Ecuavisa\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/LUcQ38Fv9Og?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>1ra Evaluaci\u00f3n 2025-2026 PAO I. 1\/Julio\/2025 Tema 3 (30 puntos) El avistamiento de ballenas es una actividad popular en Ecuador que atrae a miles de&nbsp;turistas cada a\u00f1o. Puerto L\u00f3pez, en la provincia de Manab\u00ed, a 219 kil\u00f3metros de Guayaquil, es uno de los epicentros de esta actividad.Esta peque\u00f1a localidad costera celebra anualmente el Festival de [&hellip;]<\/p>\n","protected":false},"author":8043,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"wp-custom-template-entrada-mn","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[60],"class_list":["post-11227","post","type-post","status-publish","format-standard","hentry","category-mn-1eva30","tag-interpolacion-polinomica"],"_links":{"self":[{"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/posts\/11227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/users\/8043"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/comments?post=11227"}],"version-history":[{"count":4,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/posts\/11227\/revisions"}],"predecessor-version":[{"id":14295,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/posts\/11227\/revisions\/14295"}],"wp:attachment":[{"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/media?parent=11227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/categories?post=11227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/tags?post=11227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}