{"id":14381,"date":"2023-07-08T14:10:17","date_gmt":"2023-07-08T19:10:17","guid":{"rendered":"http:\/\/blog.espol.edu.ec\/ccpg1001\/?p=13409"},"modified":"2026-08-02T15:44:52","modified_gmt":"2026-08-02T20:44:52","slug":"1eva2023paoi_t5-funcion-buscar-divisibles","status":"publish","type":"post","link":"https:\/\/blog.espol.edu.ec\/algoritmos101\/fp-1eva30\/1eva2023paoi_t5-funcion-buscar-divisibles\/","title":{"rendered":"1Eva2023PAOI_T5 Funci\u00f3n buscar divisibles en lista"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">1ra Evaluaci\u00f3n I T\u00e9rmino 2023-2024, Julio 7, 2023 \/CCPG1043<\/h2>\n\n\n\n<p><strong>Tema 4<\/strong>. (25 puntos) Implemente la funci\u00f3n <code><strong>buscar_divisibles<\/strong>(<strong>numeros<\/strong>,<em><strong>divisor<\/strong><\/em>)<\/code> que recibe como primer par\u00e1metro una lista con <strong>n\u00fameros<\/strong> enteros y como segundo par\u00e1metro un n\u00famero entero positivo mayor a 0.<\/p>\n\n\n\n<p>La funci\u00f3n retorna una nueva lista con los n\u00fameros que son <em><strong>divisible<\/strong><\/em>s para el n\u00famero recibido en el segundo par\u00e1metro.<\/p>\n\n\n\n<p>Luego, implemente un programa principal y realice lo siguiente:<\/p>\n\n\n\n<p>a. Genere una lista de 20 <strong>n\u00fameros<\/strong> aleatorios entre 2 y 200<\/p>\n\n\n\n<p>b. Genere un n\u00famero <strong>aleatorio<\/strong> entre 2 y 10.<\/p>\n\n\n\n<p>c. Llame a la funci\u00f3n con la lista de <strong>n\u00fameros<\/strong> y n\u00famero <strong>aleatorio<\/strong> generados en los pasos anteriores y muestre la lista <strong>resulta<\/strong>nte.<\/p>\n\n\n\n<p>Ejemplo de entrada<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code><strong>numeros<\/strong>_aleatorios = &#091;81, 153, 192, 77, 70, 87,\n 182, 100, 171, 157, 132, 193, 170, 95, 173, 27,\n 98, 6, 44, 34]\n<strong>divisor<\/strong> = 9<\/code><\/pre>\n\n\n\n<p>Ejemplo de salida<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>&#091;81, 153, 171, 27]<\/code><\/pre>\n\n\n\n<p><strong>Referencia<\/strong>: <a href=\"https:\/\/blog.espol.edu.ec\/algoritmos101\/fp-eval\/fp-2e05\/2eva2002tii_t1-numero-perfecto\/\" data-type=\"post\" data-id=\"2843\">2Eva2002TII_T1 Verificar si es \"N\u00famero perfecto\"<\/a><br><a href=\"https:\/\/blog.espol.edu.ec\/algoritmos101\/fp-unidades\/fp-u02\/operaciones-basicas\/#residuo\">Residuo de a para b<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>1ra Evaluaci\u00f3n I T\u00e9rmino 2023-2024, Julio 7, 2023 \/CCPG1043 Tema 4. (25 puntos) Implemente la funci\u00f3n buscar_divisibles(numeros,divisor) que recibe como primer par\u00e1metro una lista con n\u00fameros enteros y como segundo par\u00e1metro un n\u00famero entero positivo mayor a 0. La funci\u00f3n retorna una nueva lista con los n\u00fameros que son divisibles para el n\u00famero recibido en [&hellip;]<\/p>\n","protected":false},"author":8043,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"wp-custom-template-entrada-fp-ejercicios","format":"standard","meta":{"footnotes":""},"categories":[116],"tags":[146,149,155],"class_list":["post-14381","post","type-post","status-publish","format-standard","hentry","category-fp-1eva30","tag-aleatorios","tag-arreglos-vectores","tag-funciones"],"_links":{"self":[{"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/posts\/14381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/users\/8043"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/comments?post=14381"}],"version-history":[{"count":5,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/posts\/14381\/revisions"}],"predecessor-version":[{"id":22690,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/posts\/14381\/revisions\/22690"}],"wp:attachment":[{"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/media?parent=14381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/categories?post=14381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/tags?post=14381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}