{"id":17820,"date":"2017-09-18T07:10:17","date_gmt":"2017-09-18T12:10:17","guid":{"rendered":"http:\/\/blog.espol.edu.ec\/telg1001\/?p=3223"},"modified":"2026-08-01T08:32:20","modified_gmt":"2026-08-01T13:32:20","slug":"s1eva2009tii_t3-lti-ct-yt-terminos-escalon-desplazados","status":"publish","type":"post","link":"https:\/\/blog.espol.edu.ec\/algoritmos101\/ss-s1eva\/s1eva2009tii_t3-lti-ct-yt-terminos-escalon-desplazados\/","title":{"rendered":"s1Eva2009TII_T3 LTI CT y(t) desde h(t) y x(t) con t\u00e9rminos escal\u00f3n desplazados"},"content":{"rendered":"\n<p><em><strong>Ejercicio<\/strong><\/em>: <a href=\"https:\/\/blog.espol.edu.ec\/algoritmos101\/ss-1eva\/1eva2009tii_t3-lti-ct-ytdesdehtxt-terminos-escalon-desplazados\/\" data-type=\"post\" data-id=\"1604\">1Eva2009TII_T3 LTI CT y(t) desde h(t) y x(t) con t\u00e9rminos escal\u00f3n desplazados<\/a><\/p>\n\n\n\n<p>La funci\u00f3n de transferencia h(t) y la se\u00f1al de entrada x(t) son,<\/p>\n\n\n\n<p class=\"has-text-align-center\">x(t) = 2 \u03bc(t-1) - 2 \u03bc(t-3)<\/p>\n\n\n\n<p class=\"has-text-align-center\">h(t) = \u03bc(t+1) - 2 \u03bc(t-1) + \u03bc(t-3)<\/p>\n\n\n\n<p>La primera observaci\u00f3n es que h(t) h(t) tiene un <strong>componente No causal<\/strong>, que se adelanta en tiempo \u03bc(t+1) a x(t). La transformada unilateral de Laplace no aplica para este t\u00e9rmino, por lo que para el algoritmo se usa la entrada X(s) y se evita el error en la transformada. Por lo dem\u00e1s el algoritmo funciona bien.<\/p>\n\n\n\n<p><em><strong>Tarea<\/strong><\/em>: Revisar y justificar<\/p>\n\n\n\n<p>Usando la funci\u00f3n de transferencia h(t) con las transformadas de Laplace H(s)<\/p>\n\n\n<span class=\"wp-katex-eq katex-display\" data-display=\"true\"> H(s) = \\frac{1}{s}e^{s} - 2\\frac{1}{s}e^{-s}+ \\frac{1}{s} e^{-3s}<\/span>\n\n\n\n<p>simplificando la expresi\u00f3n como F(s)*(terminos exponenciales)<\/p>\n\n\n<span class=\"wp-katex-eq katex-display\" data-display=\"true\"> H(s) = \\frac{1}{s} \\Big[ e^{s} - 2e^{-s}+ e^{-3s} \\Big] <\/span>\n\n\n\n<p>tiene la forma gr\u00e1fica,<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"574\" height=\"437\" src=\"http:\/\/blog.espol.edu.ec\/algoritmos101\/files\/2017\/09\/s1Eva2009TII_T3_LTI_ht.png\" alt=\"s1Eva2009TII_T3 LTI ht\" class=\"wp-image-19775\" \/><\/figure>\n\n\n\n<p>La se\u00f1al de entrada usando las transformadas de Laplace X(s)<\/p>\n\n\n<span class=\"wp-katex-eq katex-display\" data-display=\"true\"> X(s) = 2\\frac{1}{s}e^{-s} - 2\\frac{1}{s}e^{-3s} <\/span>\n\n\n<span class=\"wp-katex-eq katex-display\" data-display=\"true\"> X(s) = \\frac{2}{s} \\Big[e^{-s} - e^{-3s} \\Big] <\/span>\n\n\n\n<p>La se\u00f1al de salida Y(s)=H(s)*X(s)<\/p>\n\n\n<span class=\"wp-katex-eq katex-display\" data-display=\"true\"> Y(s) = \\frac{2}{s^2} \\Big[ e^{s} - 2e^{-s}+ e^{-3s} \\Big] \\Big[e^{-s} - e^{-3s} \\Big] <\/span>\n\n\n\n<p>multiplicando los t\u00e9rminos de exponenciales<\/p>\n\n\n<span class=\"wp-katex-eq katex-display\" data-display=\"true\"> Y(s) = \\frac{2}{s^2} \\Big[ e^{s}e^{-s} - 2e^{-s}e^{-s}+ e^{-3s}e^{-s} - e^{s}e^{-3s} + 2e^{-s}e^{-3s} - e^{-3s}e^{-3s} \\Big] <\/span>\n\n\n<span class=\"wp-katex-eq katex-display\" data-display=\"true\"> Y(s) = \\frac{2}{s^2} \\Big[ 1 - 2e^{-2s}+ e^{-4s}- e^{-2s} + 2e^{-4s} - e^{-6s} \\Big] <\/span>\n\n\n<span class=\"wp-katex-eq katex-display\" data-display=\"true\"> Y(s) = \\frac{2}{s^2} \\Big[ 1 - 3e^{-2s}+ 3e^{-4s} - e^{-6s} \\Big] <\/span>\n\n\n\n<p>usando la <a href=\"https:\/\/blog.espol.edu.ec\/algoritmos101\/ss-unidades\/ss-u04\/transformada-laplace-tabla\/\" data-type=\"post\" data-id=\"1344\">tabla de transformadas de Laplace<\/a> en forma inversa:<\/p>\n\n\n<span class=\"wp-katex-eq katex-display\" data-display=\"true\"> y(t) = 2 (t) \\mu (t) -6 (t-2) \\mu (t-2) +6(t-4) \\mu (t-4) -2(t-6) \\mu(t-6) \\Big] <\/span>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"567\" height=\"436\" src=\"http:\/\/blog.espol.edu.ec\/algoritmos101\/files\/2017\/09\/s1Eva2009TII_T3_LTI_xh_y.png\" alt=\"s1Eva2009TII_T3 LTI xh y\" class=\"wp-image-19776\" \/><\/figure>\n\n\n\n<p>La respuesta al impulso H(s)no tiene polos en el lado derecho del plano s, por lo que las salidas son acotadas, en consecuencia el sistema es asintoticamente estable y tambi\u00e9n BiBO estable.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"447\" src=\"http:\/\/blog.espol.edu.ec\/algoritmos101\/files\/2017\/09\/s1Eva2009TII_T3_LTI_polos_Hs.png\" alt=\"s1Eva2009TII_T3 LTI polos Hs\" class=\"wp-image-19777\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>usando el algoritmo, considerando que las condiciones iniciales son cero,:<\/p>\n\n\n\n<pre class=\"wp-block-code alignwide\"><code> H(s) = P(s)\/Q(s):\n s      -s    -3*s\ne    2*e     e    \n-- - ----- + -----\ns      s       s  \n H(s) en factores:\n s      -s    -3*s\ne    2*e     e    \n-- - ----- + -----\ns      s       s  \n\n h(t) :\nHeaviside(t - 3) - 2*Heaviside(t - 1) + Heaviside(t + 1)\n\npolosceros:\nexp(s) : {'Q_polos': {0: 1}, 'P_ceros': {}, 'Hs_k': 1\/s}\nexp(-3*s) : {'Q_polos': {0: 1}, 'P_ceros': {}, 'Hs_k': 1\/s}\nexp(-s) : {'Q_polos': {0: 1}, 'P_ceros': {}, 'Hs_k': -2\/s}\nQ_polos : {0: 1}\nP_ceros : {}\n\nEstabilidad de H(s):\n n_polos_real : 0\n n_polos_imag : 1\n enRHP : 0\n unicos : 0\n repetidos : 0\n asintota : estable\n\n X(s): \n   -s      -3*s\n2*e     2*e    \n----- - -------\n  s        s   \n\nRespuesta entrada cero ZIR H(s) y condiciones iniciales\nterm_cero : 0\nZIR :\n0\nyt_ZIR :\n0\n\n ZSR respuesta estado cero:\nZSR :\n        -2*s      -4*s      -6*s\n2    6*e       6*e       2*e    \n-- - ------- + ------- - -------\n 2       2         2         2  \ns       s         s         s   \nyt_ZSR :\n2*t*Heaviside(t) + (12 - 6*t)*Heaviside(t - 2) + (12 - 2*t)*Heaviside(t - 6) +\n (6*t - 24)*Heaviside(t - 4)\n\n Y(s)_total = ZIR + ZSR:\n        -2*s      -4*s      -6*s\n2    6*e       6*e       2*e    \n-- - ------- + ------- - -------\n 2       2         2         2  \ns       s         s         s   \n\n y(t)_total = ZIR + ZSR:\n2*t*Heaviside(t) + (12 - 6*t)*Heaviside(t - 2) + (12 - 2*t)*Heaviside(t - 6) +\n (6*t - 24)*Heaviside(t - 4)\n&gt;&gt;&gt;\n<\/code><\/pre>\n\n\n\n<p>Usando los bloques desarrollados en la\u00a0<span class=\"collapsing categories expand\"><a href=\"https:\/\/blog.espol.edu.ec\/algoritmos101\/senales\/ss-unidades\/#unidad4\">Unidad 4 Sistemas LTI \u2013 Laplace<\/a><\/span>\u00a0 y las funciones resumidas como <strong><a href=\"https:\/\/blog.espol.edu.ec\/algoritmos101\/senales\/ss-algoritmos-telg1001-py\/\" data-type=\"page\" data-id=\"17852\">telg1001.py<\/a><\/strong> que pueden ser usados en cada pregunta.<\/p>\n\n\n<div class=\"wp-block-syntaxhighlighter-code alignwide\"><pre class=\"brush: python; title: ; notranslate\" title=\"\">\n# Y(s) Respuesta total con entada cero y estado cero\n# Qs Y(s) = Ps X(s) ; H(s)=Ps\/Qs\n# https:\/\/blog.espol.edu.ec\/algoritmos101\/senales\nimport sympy as sym\nimport matplotlib.pyplot as plt\nimport telg1001 as fcnm\n\n# INGRESO\ns = sym.Symbol('s')\nt = sym.Symbol('t', real=True)\nd = sym.DiracDelta(t)\nu = sym.Heaviside(t)\n\n# H(s) respuesta impulso\nHs = sym.exp(s)\/s - 2*sym.exp(-s)\/s + sym.exp(-3*s)\/s\n\n# X(s) Se\u00f1al de entrada\nxt = 2*u.subs(t,t-1) - 2*u.subs(t,t-3)\n\n# condiciones iniciales, &#x5B;y'(0),y(0)] orden descendente\nt0 = 0\ncond_inicio = &#x5B;0] # estado cero no se usan\n\n# Grafica, intervalo tiempo &#x5B;t_a,t_b]\nt_a = -2 ; t_b = 8\nmuestras = 101  # 51 resolucion grafica\n\n# PROCEDIMIENTO\nHs = fcnm.apart_s(Hs) # fracciones parciales\nHs_fc = fcnm.factor_exp(Hs) # en factores\nHs_Qs2 = fcnm.Q_cuad_s_parametros(Hs_fc)\n\npolosceros = fcnm.busca_polosceros(Hs)\nQ_polos = polosceros&#x5B;'Q_polos']\nP_ceros = polosceros&#x5B;'P_ceros']\n\nestable = fcnm.estabilidad_asintotica_s(Q_polos)\n\n# H(t) respuesta al impulso\nht = 0*s\nterm_suma = sym.Add.make_args(Hs)\nfor term_k in term_suma:\n    ht_k = sym.inverse_laplace_transform(term_k,s,t)\n    # simplifica log(exp()) ej: e**(-2s)\/(s**2)\n    if ht_k.has(sym.log):\n        ht_k = sym.simplify(ht_k,inverse=True)\n    ht  = ht + ht_k\nlista_escalon = ht.atoms(sym.Heaviside)\nht = sym.expand(ht,t) # terminos suma\nht = sym.collect(ht,lista_escalon)\n\n# PROCEDIMIENTO Respuesta ZIR, ZSR\nXs = fcnm.laplace_transform_suma(xt)\n\n# ZIR_s respuesta entrada cero de s\nsol_ZIR = fcnm.respuesta_ZIR_s(Hs,cond_inicio)\nZIR = sol_ZIR&#x5B;'ZIR']\nyt_ZIR = sol_ZIR&#x5B;'yt_ZIR']\n\n# ZSR respuesta estado cero, Y(s) a entrada X(s)\nsol_ZSR = fcnm.respuesta_ZSR_s(Hs,Xs)\nZSR = sol_ZSR&#x5B;'ZSR']\nyt_ZSR = sol_ZSR&#x5B;'yt_ZSR']\n\n# Respuesta total Y(s) y y(t)\nYs = ZIR + ZSR\nYs = fcnm.apart_s(Ys)\nyt = yt_ZIR + yt_ZSR\nlista_escalon = yt.atoms(sym.Heaviside)\nyt = sym.collect(yt,lista_escalon)\n\n# SALIDA\nprint(' H(s) = P(s)\/Q(s):')\nsym.pprint(Hs)\nprint(' H(s) en factores:')\nsym.pprint(Hs_fc)\nif len(Hs_Qs2)&gt;0:\n    print('\\nH(s) par\u00e1metros cuadraticos:')\n    fcnm.print_resultado_dict(Hs_Qs2)\n\nprint('\\n h(t) :')\nsym.pprint(ht)\n\nprint('\\npolosceros:')\nfcnm.print_resultado_dict(polosceros)\n\nprint('\\nEstabilidad de H(s):')\nfor k in estable:\n    print('',k,':',estable&#x5B;k])\n\nprint('\\n X(s): ')\nsym.pprint(Xs)\nprint('\\nRespuesta entrada cero ZIR H(s) y condiciones iniciales')\n\nif not(sol_ZIR == sym.nan): # existe resultado\n    fcnm.print_resultado_dict(sol_ZIR)\nelse:\n    print(' insuficientes condiciones iniciales')\n    print(' revisar los valores de cond_inicio&#x5B;]')\n\nprint('\\n ZSR respuesta estado cero:')\nfcnm.print_resultado_dict(sol_ZSR)\n\nprint('\\n Y(s)_total = ZIR + ZSR:')\nsym.pprint(Ys)\nprint('\\n y(t)_total = ZIR + ZSR:')\nsym.pprint(yt)\n\n# Graficas polos, H(s), con polos h(t) --------\nmuestras_H = 101\nfigura_s  = fcnm.graficar_Fs(Hs_fc,Q_polos,P_ceros,f_nombre='H',solopolos=True)\nfigura_Hs = fcnm.graficar_Fs(Hs_fc,Q_polos,P_ceros,muestras=muestras_H,f_nombre='H')\n#figura_ht = fcnm.graficar_ft(ht,t_a,t_b,muestras,f_nombre='h')\n# GRAFICAS y(t),x(t),h(t) ---------------------\nfigura_ft = fcnm.graficar_xh_y(xt,0*t,yt,t_a,t_b,muestras)\nplt.show()\n<\/pre><\/div>","protected":false},"excerpt":{"rendered":"<p>Ejercicio: 1Eva2009TII_T3 LTI CT y(t) desde h(t) y x(t) con t\u00e9rminos escal\u00f3n desplazados La funci\u00f3n de transferencia h(t) y la se\u00f1al de entrada x(t) son, x(t) = 2 \u03bc(t-1) - 2 \u03bc(t-3) h(t) = \u03bc(t+1) - 2 \u03bc(t-1) + \u03bc(t-3) La primera observaci\u00f3n es que h(t) h(t) tiene un componente No causal, que se adelanta [&hellip;]<\/p>\n","protected":false},"author":8043,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"wp-custom-template-entrada-ss-ejercicios","format":"standard","meta":{"footnotes":""},"categories":[184],"tags":[58,199],"class_list":["post-17820","post","type-post","status-publish","format-standard","hentry","category-ss-s1eva","tag-ejemplos-python","tag-senalessistemas"],"_links":{"self":[{"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/posts\/17820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/users\/8043"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/comments?post=17820"}],"version-history":[{"count":7,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/posts\/17820\/revisions"}],"predecessor-version":[{"id":24199,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/posts\/17820\/revisions\/24199"}],"wp:attachment":[{"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/media?parent=17820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/categories?post=17820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/tags?post=17820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}