{"id":632,"date":"2017-12-08T18:05:32","date_gmt":"2017-12-08T23:05:32","guid":{"rendered":"http:\/\/blog.espol.edu.ec\/matg1013\/?p=632"},"modified":"2026-07-30T09:30:30","modified_gmt":"2026-07-30T14:30:30","slug":"3eva2008tii_t2-potencia-de-traccion","status":"publish","type":"post","link":"https:\/\/blog.espol.edu.ec\/algoritmos101\/mn-3eva10\/3eva2008tii_t2-potencia-de-traccion\/","title":{"rendered":"3Eva2008TII_T2 Potencia de tracci\u00f3n"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">3ra Evaluaci\u00f3n II T\u00e9rmino 2008-2009. 3\/Marzo\/2009. ICM00158<\/h2>\n\n\n\n<p><strong>Tema 2<\/strong>. <\/p>\n\n\n\n<figure class=\"wp-block-image alignright size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"201\" height=\"265\" src=\"http:\/\/blog.espol.edu.ec\/algoritmos101\/files\/2017\/12\/servoMotor01.png\" alt=\"servo Motor\" class=\"wp-image-17765\" \/><\/figure>\n\n\n\n<p>Un servomecanismo presenta la <strong>potencia de tracci\u00f3n<\/strong> en funci\u00f3n del <strong>\u00e1ngulo de elevaci\u00f3n<\/strong> como se indica en la tabla.<\/p>\n\n\n\n<p>a. Construya el trazador c\u00fabico natural<\/p>\n\n\n\n<p>b. Aproxime la potencia cuando el \u00e1ngulo es 35 grados, y determine el error de interpolaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-table alignwide\"><table><tbody><tr><td>Elevaci\u00f3n (grados)<\/td><td>&nbsp;20<\/td><td>30<\/td><td>40<\/td><td>50<\/td><td>60<\/td><\/tr><tr><td>Potencia (Joules\/s)<\/td><td>34.202,00<\/td><td>50.000,00<\/td><td>64.279,00<\/td><td>76.604,00,00<\/td><td>86.603,00<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<pre class=\"wp-block-code\"><code>elevacion = &#091; 20, 30, 40, 50, 60]\npotencia  = &#091;34202, 50000, 64279, 76604, 86603]<\/code><\/pre>\n\n\n\n<p><strong>Referencia<\/strong>: \u00bfCu\u00e1nto peso levanta un brazo rob\u00f3tico arduino? How much weight a robotic arm can lift? SERVOMOTOR. Ciencia y proyectos escolares. 30 abril 2020<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\u00bfCu\u00e1nto peso levanta un brazo rob\u00f3tico arduino? How much weight a robotic arm can lift? SERVOMOTOR\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/3bGpG3xzImg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>3ra Evaluaci\u00f3n II T\u00e9rmino 2008-2009. 3\/Marzo\/2009. ICM00158 Tema 2. Un servomecanismo presenta la potencia de tracci\u00f3n en funci\u00f3n del \u00e1ngulo de elevaci\u00f3n como se indica en la tabla. a. Construya el trazador c\u00fabico natural b. Aproxime la potencia cuando el \u00e1ngulo es 35 grados, y determine el error de interpolaci\u00f3n. Elevaci\u00f3n (grados) &nbsp;20 30 40 [&hellip;]<\/p>\n","protected":false},"author":8043,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"wp-custom-template-entrada-mn","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[60],"class_list":["post-632","post","type-post","status-publish","format-standard","hentry","category-mn-3eva10","tag-interpolacion-polinomica"],"_links":{"self":[{"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/posts\/632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/users\/8043"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/comments?post=632"}],"version-history":[{"count":4,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/posts\/632\/revisions"}],"predecessor-version":[{"id":25170,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/posts\/632\/revisions\/25170"}],"wp:attachment":[{"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/media?parent=632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/categories?post=632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.espol.edu.ec\/algoritmos101\/wp-json\/wp\/v2\/tags?post=632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}