{"id":218,"date":"2011-08-29T09:33:45","date_gmt":"2011-08-29T14:33:45","guid":{"rendered":"http:\/\/blog.espol.edu.ec\/gchavez\/?p=218"},"modified":"2011-08-29T09:33:45","modified_gmt":"2011-08-29T14:33:45","slug":"%c2%bfamigos","status":"publish","type":"post","link":"https:\/\/blog.espol.edu.ec\/gchavez\/2011\/08\/29\/%c2%bfamigos\/","title":{"rendered":"\u00bfAmigos?"},"content":{"rendered":"<p style=\"text-align: justify\">Se me ocurri\u00f3 que deb\u00eda escribir a mis amigos un mail preguntando c\u00f3mo se desarrollaba su vida lejos de la ciudad donde resido. Pens\u00e9: \u00a1c\u00f3mo los extra\u00f1o! Y luego: \u00bfme extra\u00f1an ellos tambi\u00e9n? Era una pregunta dif\u00edcil de responder, ya que no soy ellos para hacerlo. Sin embargo, decid\u00ed que s\u00ed,\u00a0 ellos tambi\u00e9n me recuerdan con cari\u00f1o. Fue as\u00ed como empec\u00e9 a escribir a los panas la primera carta. Se form\u00f3 un di\u00e1logo cordial, de amigos que se estiman y a\u00f1oran su compa\u00f1\u00eda en un nuevo ambiente extra\u00f1o a\u00fan. Pronto, la vida se torn\u00f3 dif\u00edcil, el tiempo escaseaba, pero enviaba alguna vez una carta que era respondida con igual dificultad. Tiempo despu\u00e9s, en el momento en el que las personas logran establecerse en su nuevo sitio, fue imposible destinar una carta a mis amigos. Sent\u00ed nostalgia y congoja por esta nueva situaci\u00f3n. Con todo, pens\u00e9 si ellos me escriben har\u00e9 todo el esfuerzo necesario para responder. Esper\u00e9. Segu\u00ed esperando largo tiempo, hasta que pude enviar alguna se\u00f1al de vida y me respondieron algunos, no todos.<\/p>\n<p style=\"text-align: justify\">Ahora pienso: \u00bfpor qu\u00e9 soy yo el que tiene que acordarse de ellos? \u00bfEs muy dif\u00edcil para ellos dedicar unos minutos a sus amigos? \u00bfAmigos? Excelsa palabra, desgastada por el banal uso que de ella se hace. Panas en la juerga, en las buenas \u00e9pocas, cuando te necesito\u2026 Pero, \u00bfes ese el caso de los que yo llamo amigos? \u00a1No! Me niego a creer que ellos entran en esa clasificaci\u00f3n. Simplemente es mi ego\u00edsmo el que me lleva a pensar de esta forma. Deben dedicar su tiempo al estudio, a sus nuevos y a los otros viejos amigos, a su familia\u2026 porque no soy YO el \u00fanico en el mundo.<\/p>\n<p style=\"text-align: justify\">En este instante me doy cuenta que un amigo es aquel que de lo que lleva dentro da a los que est\u00e1n m\u00e1s cerca. Aqu\u00e9l que vive fuera de s\u00ed, d\u00e1ndose a los dem\u00e1s. Que aun estando cansado saca tiempo para el resto. Que est\u00e1 dispuesto a dar su vida por un amigo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se me ocurri\u00f3 que deb\u00eda escribir a mis amigos un mail preguntando c\u00f3mo se desarrollaba su vida lejos de la ciudad donde resido. Pens\u00e9: \u00a1c\u00f3mo los extra\u00f1o! Y luego: \u00bfme extra\u00f1an ellos tambi\u00e9n? Era una pregunta dif\u00edcil de responder, ya &hellip; <a href=\"https:\/\/blog.espol.edu.ec\/gchavez\/2011\/08\/29\/%c2%bfamigos\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":931,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13449],"tags":[3415,498,153,39817,40509],"class_list":["post-218","post","type-post","status-publish","format-standard","hentry","category-escritos","tag-amigo","tag-amistad","tag-amor","tag-gabo21","tag-pana"],"_links":{"self":[{"href":"https:\/\/blog.espol.edu.ec\/gchavez\/wp-json\/wp\/v2\/posts\/218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.espol.edu.ec\/gchavez\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.espol.edu.ec\/gchavez\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.espol.edu.ec\/gchavez\/wp-json\/wp\/v2\/users\/931"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.espol.edu.ec\/gchavez\/wp-json\/wp\/v2\/comments?post=218"}],"version-history":[{"count":2,"href":"https:\/\/blog.espol.edu.ec\/gchavez\/wp-json\/wp\/v2\/posts\/218\/revisions"}],"predecessor-version":[{"id":256,"href":"https:\/\/blog.espol.edu.ec\/gchavez\/wp-json\/wp\/v2\/posts\/218\/revisions\/256"}],"wp:attachment":[{"href":"https:\/\/blog.espol.edu.ec\/gchavez\/wp-json\/wp\/v2\/media?parent=218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.espol.edu.ec\/gchavez\/wp-json\/wp\/v2\/categories?post=218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.espol.edu.ec\/gchavez\/wp-json\/wp\/v2\/tags?post=218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}